{"id":11884,"date":"2020-10-17T11:24:35","date_gmt":"2020-10-17T11:24:35","guid":{"rendered":"http:\/\/100hearts.com.sg\/data\/?p=11884"},"modified":"2020-10-06T06:24:20","modified_gmt":"2020-10-06T06:24:20","slug":"se-rencontrer-guyane","status":"publish","type":"post","link":"https:\/\/100hearts.com.sg\/data\/2020\/10\/17\/se-rencontrer-guyane\/","title":{"rendered":"Se Rencontrer Guyane"},"content":{"rendered":"<p>Participe \u00e0 la d\u00e9finition densemble de la strat\u00e9gie acad\u00e9mique qui met en \u0153uvre la politique \u00e9ducative et p\u00e9dagogique relative aux enseignements primaires et secondaires arr\u00eat\u00e9e par le ministre charg\u00e9 de l\u00e9ducation Coronavirus dans le monde : le cap des 300.000 d\u00e9c\u00e8s franchi alors que lEurope se d\u00e9confine peu \u00e0 peu plus de 30 de la production agricole finale, et 79.000 tonnes Le taux dabstention a \u00e9t\u00e9 particuli\u00e8rement fort lors de cette \u00e9lection pr\u00e9sidentielle, du fait du mouvement social dune ampleur consid\u00e9rable qui a eu lieu dans les semaines qui lont pr\u00e9c\u00e9d\u00e9e. Ce mouvement aux revendications multiples exigeait plus de services publics, mais a \u00e9galement remis en cause les mani\u00e8res h\u00e9t\u00e9ronomes de gouverner le peyi, et exprimait la volont\u00e9 de reprendre la main sur les affaires qui le concernent. Cest ainsi que certains des manifestants appelaient au boycott des \u00e9lections pr\u00e9sidentielles. Labstention a de fait \u00e9t\u00e9 plus forte que lors de l\u00e9lection pr\u00e9sidentielle de 2012, o\u00f9 elle repr\u00e9sentait quand m\u00eame d\u00e9j\u00e0 plus de 49 au premier tour. En Guyane, on regarde toujours avec distance les d\u00e9bats de la campagne pr\u00e9sidentielle, dont les enjeux sont tr\u00e8s \u00e9loign\u00e9s des pr\u00e9occupations quotidiennes. Il faut remettre les scores des diff\u00e9rents candidats \u00e0 leur place : Jean-Luc M\u00e9lenchon a \u00e9t\u00e9 plac\u00e9 en t\u00eate du premier tour avec 6 633 voix, mais cela ne repr\u00e9sente pas lensemble de la population de la Guyane, recens\u00e9e \u00e0 252 338 personnes par lINSEE et leurs chiffres sont probablement en de\u00e7\u00e0 de la r\u00e9alit\u00e9. Cette population est tr\u00e8s jeune, en grande partie de nationalit\u00e9 \u00e9trang\u00e8re : beaucoup dhabitants nont donc pas le droit de vote, ce \u00e0 quoi sajoutent labstention et la non-inscription sur les listes \u00e9lectorales. Lezy, Emmanuel, 1998, fragments dun voyage aux Guyanes, dans Guyanes-Guyane, perceptions et repr\u00e9sentations de lespace compris entre lAmazone et lOr\u00e9noque, Th\u00e8se de Doctorat de G\u00e9ographie de lUniversit\u00e9 de Paris X Nanterre, sous la direction de Jean-Pierre Raison. Apr\u00e8s un petit-d\u00e9jeuner matinal, vous vous dirigez vers Kourou o\u00f9 se trouve lunique base de lancement spatial dEurope. Sur place, une visite guid\u00e9e vous emm\u00e8ne au coeur des centres de contr\u00f4le, mais aussi sur les zones de lancement dAriane 5, Soyouz et de Vega. <img decoding=\"async\" src=\"http:\/\/www.blog-trotteurs.com\/wp-content\/uploads\/2014\/08\/faune_chiffres.png\" alt=\"se rencontrer guyane\" align=\"center\"> La d\u00e9cision de r\u00e9ouverture avec une telle pr\u00e9cipitation montre une fois encore quil sagit avant tout pour le gouvernement de permettre aux entreprises de faire revenir les salari\u00e9-e-s sur le lieux de travail il ne sera quasiment plus possible de b\u00e9n\u00e9ficier dune autorisation dabsence pour garde denfant, et que les questions sociales et p\u00e9dagogiques ne sont donc quun alibi.  Une jeune designer de la r\u00e9gion nous parle dune nouvelle plateforme pour encourager les entrepreneurs noirs. <img decoding=\"async\" src=\"http:\/\/www.autisme-guyane.fr\/wp-content\/uploads\/logo-autisme-guyane.png\" alt=\"se rencontrer guyane\" align=\"left\">  Ceci dit, un spot est \u00e0 voir en Guyane : les \u00eeles du Salut. L\u00e0, vous aurez de leau bleue! Cest un ensemble de trois \u00eeles qui font partie int\u00e9grante de lhistoire puisquelles \u00e9taient le lieu de d\u00e9tention des bagnards. Deux sur les trois sont accessibles. Vous pourrez y voir notamment les ruines des anciennes cellules et puis vous pourrez bien \u00e9videmment vous baigner et profiter de ce cadre idyllique. R\u00e9gion Outre-Mer : La 3\u00e8me \u00e9dition de la Caravane du Logement se d\u00e9roulera en Guyane D\u00e9couvrez le magasin Pimkie le plus proche de chez vous, <img decoding=\"async\" src=\"http:\/\/images.alinfini-mariage.fr\/mariage\/2017\/collector\/17420-4.jpg\" alt=\"se rencontrer guyane\" align=\"left\"> Limmigration de travailleurs contractuels de lInde, commenc\u00e9e d\u00e8s 1856, sest poursuivi jusquen 1877 et a totalis\u00e9 8 472 personnes. Un colporteur crois\u00e9 dans la r\u00e9gion de lInipi. Il porte 50 kg et passe de campement en campement pour vendre ses produits.  Lundi, de premiers tests ont \u00e9t\u00e9 effectu\u00e9s \u00e0 lh\u00f4pital de Saint-Laurent du Maroni. L\u00e9tablissement re\u00e7oit aujourdhui un nouvel automate ainsi que des r\u00e9actifs et des \u00e9couvillons. Cest une des heureuses nouvelles de ce d\u00e9but de semaine : depuis lundi, le laboratoire du Chog teste les pr\u00e9l\u00e8vements au Covid-19. C Une \u00e9conomie plus dynamique que dans les autres d\u00e9partements Apr\u00e8s le d\u00e9put\u00e9, cest chez le roi des Alukus que nous sommes conduits. Plus pr\u00e9cis\u00e9ment, comme lannonce linscription \u00e0 lentr\u00e9e du palais : Sa majest\u00e9 Kpot\u00e9houn Allanmakoun 18eme Roi dAdjarra, intronis\u00e9 le 19 octobre 2018. Une autre inscription liste tous les rois dAdjarra qui lont pr\u00e9c\u00e9d\u00e9, jusquau fondateur Attawa, qui a r\u00e9gn\u00e9 de 1722 \u00e0 1749. Pour plus dinformations, consulter le document suivant en anglais : Face \u00e0 lhostilit\u00e9 des am\u00e9rindiens, les troupes du Roi Louis XIII ont \u00e9t\u00e9 oblig\u00e9es dabandonner la ville de Cayenne en 1643 ; mais elles ont pu la reconqu\u00e9rir en 1677. Les cultures de caf\u00e9, de coton et de cacao se sont d\u00e9velopp\u00e9es et des missions j\u00e9suites se sont install\u00e9es dans la ville. Plus tard, lesclavage a fait son apparition et la r\u00e9gion est devenue un important lieu de d\u00e9portation. Nos membres sont \u00e0 la recherche de belles histoires et nous mettons tout en \u0153uvre pour leur permettre de les vivre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>se rencontrer guyane<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/11884"}],"collection":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/comments?post=11884"}],"version-history":[{"count":1,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/11884\/revisions"}],"predecessor-version":[{"id":11885,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/11884\/revisions\/11885"}],"wp:attachment":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/media?parent=11884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/categories?post=11884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/tags?post=11884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}