{"id":12096,"date":"2020-10-18T02:47:21","date_gmt":"2020-10-18T02:47:21","guid":{"rendered":"http:\/\/100hearts.com.sg\/data\/?p=12096"},"modified":"2020-10-06T12:09:28","modified_gmt":"2020-10-06T12:09:28","slug":"le-king-rencontre-le-king","status":"publish","type":"post","link":"https:\/\/100hearts.com.sg\/data\/2020\/10\/18\/le-king-rencontre-le-king\/","title":{"rendered":"Le King Rencontre Le King"},"content":{"rendered":"<p>Rencontre Inter-CVC MLKLFA-Coll\u00e8ge Martin Luther King-Buc  Des dossiers et analyses exclusifs sur des strat\u00e9gies dentreprises Un programme propos\u00e9e par Radio Rencontre 93.3fm Dunkerque, avec la collaboration de la Maison de quartier Bayard-Villenvie, lassociation VILLENVIE, et le CEFIR. Chacun entretient avec Presley une histoire personnelle. Mathilde, 20 ans, qui la d\u00e9couvert alors que ses parents dansaient le rock, la depuis int\u00e9gr\u00e9 \u00e0 sa playlist. Love Me Tender, \u00e7a m\u00e9prend aux tripes, senthousiasme Marthe, 81 ans. Serge, 65 ans, voit en Elvis la madeleine de Proust de sa jeunesse lorsquil se rem\u00e9more les slows dans\u00e9s sur les airs langoureux-love me tender, love me sweet.. Annick, 59 ans, est plus sensible au sens des mots quil mettait en musique, comme In the Ghetto, vibrant plaidoyer contre linjustice de lexclusion. Pour elle, Elvis est lincarnation de lhomme tendre, avec sa voix troublante et chaleureuse, m\u00e9lange de virilit\u00e9 et de douceur. Mais comme une farouche combattante qui livre son experience c\u0153ur de Paris et Hong Kong, c\u00e9l\u00e9brant de fa\u00e7on ironique lalliance  en Grace Palladino, Teenagers : An American History, New York, BasicBooks, 1996, 313 p. En plus de quoi, lauteur-compositeur se gavait de rap durant lessentiel de l\u00e9criture et lenregistrement de la galette. De Kanye West \u00e0 Chance The Rapper, en passant par Young Thug, notamment : Jadore la fa\u00e7on avec laquelle ils essaient des trucs au niveau du son, il y a une vraie grande recherche. Jai limpression que le genre se renouv\u00e8le aux six mois, cest fou. \u00c0 une \u00e9mission de t\u00e9l\u00e9-r\u00e9alit\u00e9 sur une \u00eele. Isol\u00e9s du monde par la temp\u00eate, on <img decoding=\"async\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/4\/49\/Rubens_medici_cycle_meeting_at_Lyon.jpg\" alt=\"le king rencontre le king\" align=\"left\">  Quand j\u00e9tais au Lyc\u00e9e, je me sentais isol\u00e9e car on recevait une \u00e9ducation tr\u00e8s h\u00e9t\u00e9ronorm\u00e9e. Puis jai commenc\u00e9 \u00e0 mint\u00e9resser \u00e0 la litt\u00e9rature queer et je my suis retrouv\u00e9e assez rapidement. The Prince of Salt est clairement un livre qui minspire \u00e9norm\u00e9ment. Tous ces personnages queers dans un monde idyllique mont pouss\u00e9e \u00e0 massumer. Puis soyons honn\u00eate, jai aussi test\u00e9 les mecs et les bites mais jai vite compris que ce n\u00e9tait pas pour moi, ahah. En 1999, il a cofond\u00e9 la Best Friend Librairy, organisation qui regroupe une biblioth\u00e8que et un centre dinformations. Le centre est uniquement tenu par des b\u00e9n\u00e9voles et des dons de bienfaiteurs. Cest un lieu de rencontre pour les migrants birmans, les r\u00e9fugi\u00e9s et les personnes int\u00e9ress\u00e9es qui viennent du monde entier en savoir plus sur la situation des migrants birmans et sur la Birmanie. Le jour o\u00f9 jai eu ma premi\u00e8re copine! Quand tu te sens bien avec une fille, cest peut-\u00eatre le moment de comprendre que cest bon, \u00e7a y est. Vous naviguez sur le nouveau site Aller au contenu principal Aller au pied de page Quelques mois apr\u00e8s lapparition sur la sc\u00e8ne du Coachella Festival de lhologramme de Tupac, cest Elvis qui devrait reprendre le chemin des tourn\u00e9es. Nos idoles d\u00e9funtes reverront-elles toutes le jour autrement? <img decoding=\"async\" src=\"http:\/\/www.focac.org\/eng\/zywx_1\/tpz\/W020090928533932181871.jpg\" alt=\"le king rencontre le king\" align=\"right\"> Jaurais bien aim\u00e9 savoir sil avait donn\u00e9 son avis sur ladaptation en comics. Transformer un proc\u00e9d\u00e9 subversif en une rente facile au pr\u00e9texte de <img decoding=\"async\" src=\"http:\/\/www.kong.fr\/fichiers2\/pagephotos\/87\/photo\/2.jpg\" alt=\"le king rencontre le king\" align=\"center\"> La famille Vancraeyenest monte dailleurs sur la Saint-Romain depuis des d\u00e9cennies : Mes parents faisaient la foire au Boulingrin \u00e0 l\u00e9poque, ils avaient des baraques de strip-tease et de ph\u00e9nom\u00e8nes comme on disait alors. Mais les go\u00fbts ont \u00e9volu\u00e9, ces attractions nexistent plus de nos jours, observe le forain, qui sest adapt\u00e9 aux \u00e9volutions en investissant dans des man\u00e8ges modernes et attractifs pour le public La Foire Saint-Romain, \u00e0 Rouen : un \u00e9v\u00e9nement important dans le calendrier rouennais et qui attire un public consid\u00e9rable. Isabelle Villy En cochant cette case, je consens \u00e0 lutilisation des informations fournies \u00e0 des fins de marketing \u00e9lectronique. ABONNEZ-VOUS La consommation excessive de m\u00e9dicaments commence \u00e0 avoir des effets sur la sant\u00e9 de Presley. Il fait deux surdoses de en 1973 et finit \u00e0 lh\u00f4pital apr\u00e8s la seconde. Malgr\u00e9 cela, il donne de plus en plus de concerts, jusqu\u00e0 168 pour la seule ann\u00e9e 1973. Son \u00e9tat de sant\u00e9 se d\u00e9grade brutalement en septembre 1974, ce qui inqui\u00e8te ses collaborateurs, mais le public est tenu dans lignorance et continue \u00e0 assister en masse \u00e0 ses concerts. Reste cependant un magnifique spectacle, plein de bruit et de couleurs, aur\u00e9ol\u00e9 de magie et de myst\u00e8re.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>le king rencontre le king<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/12096"}],"collection":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/comments?post=12096"}],"version-history":[{"count":1,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/12096\/revisions"}],"predecessor-version":[{"id":12097,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/12096\/revisions\/12097"}],"wp:attachment":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/media?parent=12096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/categories?post=12096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/tags?post=12096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}