{"id":1229,"date":"2020-09-21T17:54:56","date_gmt":"2020-09-21T17:54:56","guid":{"rendered":"http:\/\/100hearts.com.sg\/data\/?p=1229"},"modified":"2020-09-19T21:04:30","modified_gmt":"2020-09-19T21:04:30","slug":"rencontre-roch-voisine","status":"publish","type":"post","link":"https:\/\/100hearts.com.sg\/data\/2020\/09\/21\/rencontre-roch-voisine\/","title":{"rendered":"Rencontre Roch Voisine"},"content":{"rendered":"<p>Les temps sont durs pour plusieurs entreprises qu\u00e9b\u00e9coises contraintes de mettre la cl\u00e9 sous la porte. Une fin du parcours difficile \u00e0 vivre, mldr; Je souhaite que ces 17 victimes ne soient pas d\u00e9c\u00e9d\u00e9es pour rien afin que la tol\u00e9rance triomphe, \u00e0 commencer par lacceptation de nos diff\u00e9rences qui sont une vrai richesse. <img decoding=\"async\" src=\"http:\/\/www.chartsinfrance.net\/images\/artistes\/rochvoisine.jpg\" alt=\"rencontre roch voisine\" align=\"left\"> Roch Voisine : Son coup de foudre pour sa jeune ch\u00e9rie de 25 ans sa cadette Purepeople.com purepeople Cest lensemble de toutes ces mesures.. Qui vont avoir un impact b\u00e9n\u00e9fique chez nos p\u00eacheurs, estime Martin Mallet, directeur g\u00e9n\u00e9ral de lUnion des p\u00eacheurs maritimes, organisme qui repr\u00e9sente 1300 p\u00eacheurs c\u00f4tiers du Nouveau-Brunswick et de la Nouvelle-\u00c9cosse. Roch se Shoote ind\u00e9niablement \u00e0 lamour. Et Dieu sait quil a raison le bougre. Quand on aime, je lai toujours pens\u00e9, cest pour la vie, et parfois, m\u00eame si \u00e7a para\u00eet compl\u00e8tement fou, on aime \u00e0 en mourir, comme le chantait si bien Francis Cabrel avec son inoubliable Je laime \u00e0 mourir. Un beau titre que Roch a eu la formidable id\u00e9e de traduire dans la langue de Shakespeare et quil nous offert ce soir au Grand Rex. Seule chanson francophone de son r\u00e9pertoire quil a d\u00e9cid\u00e9 dadapter dans une autre langue. Une r\u00e9ussite pour ce qu\u00e9b\u00e9cois qui explique quil na pu le faire que parce quil est fan de lauteur original. Il en a de la chance Francis Cabrel Et dire que sans son tube H\u00e9l\u00e8ne qui a failli ne jamais \u00eatre sur son disque, nous serions pass\u00e9s \u00e0 c\u00f4t\u00e9 dun simple gars au c\u0153ur dor. Heureusement, lors des s\u00e9ances denregistrements de son premier album international, le titre pr\u00e9vu initialement a disparu au profit de la charmante H\u00e9l\u00e8ne. Pour la petite histoire Apr\u00e8s deux ou trois jours de travail infructueux sur ce titre imparfait, Roch narrivait pas \u00e0 le faire sonner comme il le voulait, le chanteur a pris une grande d\u00e9cision : Roch a alors expliqu\u00e9 \u00e0 son impr\u00e9sario quil a pr\u00e9f\u00e9r\u00e9 remplacer ce morceau improbable par un titre auquel il croyait bien davantage, cest l\u00e0 qu H\u00e9l\u00e8ne est n\u00e9e et que lancien hockeyeur est devenu en quelques semaines une v\u00e9ritable star de la chanson francophone! Comme quoi, Les petits d\u00e9tails dune existence peuvent changer toute une vie, explique Roch avec une certaine \u00e9motion! <img decoding=\"async\" src=\"http:\/\/media.cheriefm.fr\/436x327\/2010\/12\/roch-voisine-3_296995.jpg\" alt=\"rencontre roch voisine\" align=\"left\"> Retour \u00e0 lexercice solo. Le concept nest pas le m\u00eame quavec Corneille et Garou \u00e9videmment, la grande diff\u00e9rence, m\u00eame si je suis entour\u00e9 dexcellents musiciens, est que la charge nest pas la m\u00eame. Cest quand m\u00eame plus facile \u00e0 trois! Mais cest une adaptation en fait, cest un peu comme se replonger dans ses baskets. Nous avons r\u00e9p\u00e9t\u00e9 \u00e0 Montr\u00e9al, on a fait quelques concerts avant No\u00ebl et voil\u00e0, on y est! 2018-09-05T11:19:2502:00 5 juillet 2018 Cat\u00e9gories : Construire le plan de tra\u00e7abilit\u00e9 des lots de production Laissez votre message \u00e0 Roch Voisine sur le r\u00e9pondeur qui lui est destin\u00e9 : 02337.60.50. En Nielsen Business Media Inc, Billboard, Nielsen Business Media, Inc, 22 mai 1993 Roch Voisine est n\u00e9 \u00e0 Edmundston au et a grandi \u00e0 pr\u00e8s de la fronti\u00e8re du. Ses parents sont Z\u00e9lande Robichaud et R\u00e9al Voisine. Il a un fr\u00e8re et une s\u0153ur, Marc et Janice. 1989 1990 1993 1994 1996 1999 2001 2003 2005 2008 2009 2010 2013 Les temps changent et la musique se consomme d\u00e9sormais avec une rapidit\u00e9 navrante. Le chanteur qu\u00e9b\u00e9cois constate, avec une pointe de regret peut \u00eatre, que beaucoup ne savent plus \u00e9couter et appr\u00e9cier la musique pour elle-m\u00eame et la r\u00e9duisent \u00e0 un bruit de fond alors m\u00eame quils se livrent \u00e0 une autre activit\u00e9. Dor\u00e9navant, Roch Voisine cherche \u00e0 satisfaire son public avec un format plus abr\u00e9g\u00e9 : Je me suis aper\u00e7u que les gens n\u00e9coutaient plus la musique de la m\u00eame mani\u00e8re. Si vous voulez aller vers le public, il faut proposer un format qui sera \u00e9cout\u00e9. Les gens sont press\u00e9s et peu attentifs, font plusieurs choses en m\u00eame temps. Cest assez rare aujourdhui, les gens qui \u00e9coutent la musique comme on le faisait \u00e0 une certaine \u00e9poque. Il faut vivre avec son temps! Si tu ne passes pas \u00e0 la radio, les gens ne savent pas que tu existes. Il faut donc proposer un format adapt\u00e9 \u00e0 la radio. Apr\u00e8s 21 albums, jai ador\u00e9 le challenge! Je suis parti de ce qui plait et ce \u00e0 quoi je me midentifie et qui marche bien, de la musique anglo-saxonne, et je me suis demand\u00e9 si on pouvait le faire en fran\u00e7ais. Jadore \u00e9couter Train et Coldplay, tous ces groupes super bien arrang\u00e9s qui me stimulent et je me suis dit que \u00e7a serait bien de le faire en fran\u00e7ais. Les insultes, les attaques personnelles, les agressions nont pas leur place dans notre espace de commentaires.  Il ny a pas de mots pour exprimer \u00e0 quel point nous sommes afflig\u00e9s par la dure perte que vous vivez. Nous esp\u00e9rons simplement que notre sympathie vous apportera un certain apaisement. Dans ces instants de grandes tristesses nos pens\u00e9es vous accompagnent, nos plus sinc\u00e8res condol\u00e9ances. Amiti\u00e9 Barbara et famille. <img decoding=\"async\" src=\"http:\/\/mimi1380.m.i.pic.centerblog.net\/j07l93kz.jpg\" alt=\"rencontre roch voisine\" align=\"center\"> Ainsi vous allez pouvoir b\u00e9n\u00e9ficier de 2 entr\u00e9es VIP, dun placement privil\u00e9gi\u00e9 en tribune assis et dun cocktail dapr\u00e8s concert avec une possible rencontre de lartiste.   Joueur de hockey \u00e0 lorigine, le canadien doit abandonner sa carri\u00e8re prometteuse \u00e0 la suite dune blessure. Il se tourne alors vers sa seconde passion : la musique. En 1989, il \u00e9crit avec son ami St\u00e9phane Lessard le titre H\u00e9l\u00e8ne qui rencontre en quelques mois un succ\u00e8s ph\u00e9nom\u00e9nal. Lalbum \u00e9ponyme bat tous les records de vente au Canada avant de conqu\u00e9rir la France. La Roch-mania est lanc\u00e9e. Sen suit une s\u00e9rie de tubes populaires et de tourn\u00e9es triomphales ainsi quune v\u00e9ritable histoire damour entre lui et le public fran\u00e7ais. 2006 : Single Le CheminNe me laisse jamais partir Nous attendons en d\u00e9but de soir\u00e9e des vents pouvant aller jusqu\u00e0 90 kmh. La Ville de Nancy fermera donc tous ses parcs de fa\u00e7on pr\u00e9ventive : En 2009, le chanteur signe lalbum Americana II suivi de Americana III California, lann\u00e9e suivante, marqu\u00e9 notamment par des reprises de Simon and Garfunkel, The Mamas and the Papas, The Byrds ou encore The Beach Boys.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>rencontre roch voisine<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/1229"}],"collection":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/comments?post=1229"}],"version-history":[{"count":1,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/1229\/revisions"}],"predecessor-version":[{"id":1230,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/posts\/1229\/revisions\/1230"}],"wp:attachment":[{"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/media?parent=1229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/categories?post=1229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/100hearts.com.sg\/data\/wp-json\/wp\/v2\/tags?post=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}